{"id":22186,"date":"2026-04-15T13:54:11","date_gmt":"2026-04-15T11:54:11","guid":{"rendered":"https:\/\/francis-mizio.net\/?p=22186"},"modified":"2026-04-13T09:42:08","modified_gmt":"2026-04-13T07:42:08","slug":"ou-etais-je-le-15-avril-2019-a-paris-pris-par-ma-propre-ignorance-ma-betise-et-un-prejuge","status":"publish","type":"post","link":"https:\/\/francis-mizio.net\/index.php\/2026\/04\/15\/ou-etais-je-le-15-avril-2019-a-paris-pris-par-ma-propre-ignorance-ma-betise-et-un-prejuge\/","title":{"rendered":"[O\u00f9 \u00e9tais-je le&#8230; ?] 15 avril 2019, \u00e0 Paris, pris par ma propre ignorance, ma b\u00eatise, un pr\u00e9jug\u00e9 et un myst\u00e8re"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">[Explications de ce projet m\u00e9moriel et nettoyeur num\u00e9rique en bas]<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span dir=\"auto\" style=\"color: #ff6600;\"><strong>Le 15 avril 2019 \u00e0 13h54<\/strong><strong>, il y a 7 <\/strong><\/span><span dir=\"auto\"><strong><span style=\"color: #ff6600;\">ans, j&rsquo;\u00e9tais rue St-Jacques \u00e0 Paris, en face de l&rsquo;\u00e9glise St-S\u00e9verin pris par ma propre ignorance, ma b\u00eatise, un pr\u00e9jug\u00e9 et un myst\u00e8re.<\/span><br \/>\n<\/strong>En passant, je vois sur le trottoir l&rsquo;\u00e9tal d&rsquo;une \u00ab\u00a0\u00e9picerie arabe\u00a0\u00bb ces cl\u00e9mentines <em>\u00ab\u00a0soculentes\u00a0\u00bb<\/em>. Je postai alors cette image sur Instagram (o\u00f9 j&rsquo;allais encore \u00e0 l&rsquo;\u00e9poque), car cela me fit rire (d\u00e9j\u00e0 : ce ne sont pas des mandarines, mais ce n&rsquo;est pas le c\u0153ur du probl\u00e8me) : en effet, je crus que le commer\u00e7ant avait r\u00e9dig\u00e9 son panonceau entre fautes de fran\u00e7ais et accent m\u00e9diterran\u00e9en, ayant voulu promouvoir qu&rsquo;elles \u00e9taient <em>succulentes<\/em>. En fait, <span style=\"color: #ff6600;\"><strong>l&rsquo;ignare, c&rsquo;\u00e9tait bien moi, car plus tard je d\u00e9couvre que<\/strong><\/span>\u00a0<strong><a href=\"https:\/\/shop.les4saisonsduvexin.com\/index.php\/produit\/clementines-la-soculente\/\" target=\"_blank\" rel=\"noopener\">les cl\u00e9mentines <em>soculente<\/em>\u00a0sont une vari\u00e9t\u00e9 commerciale<\/a>. <\/strong>(Et il m&rsquo;aurait suffit en sus de lire le papier d&#8217;emballage des fruits pour le constater ! Mais voil\u00e0, on prend une photo, on ne r\u00e9fl\u00e9chit pas, on poste aussit\u00f4t. Les r\u00e9seaux rendent cr\u00e9tin&#8230;). <span style=\"color: #ff6600;\"><strong>Cela \u00e9tant, la recherche de l&rsquo;origine de ce nom, qui rel\u00e8verait du marketing, ne donne jamais rien de pr\u00e9cis.<\/strong><\/span> M\u00eame Perplexity nous dit : <em>\u00ab\u00a0Le nom \u00ab Soculente \u00bb n\u2019est pas l\u2019origine historique du mot cl\u00e9mentine : c\u2019est un nom commercial qui joue sur l\u2019id\u00e9e d\u2019un fruit tr\u00e8s juteux et gourmand. L\u2019origine du nom de la cl\u00e9mentine, elle, vient du p\u00e8re Cl\u00e9ment \u2014 aussi appel\u00e9 fr\u00e8re Cl\u00e9ment Rodier \u2014 un religieux agronome qui travaillait \u00e0 Misserghin, pr\u00e8s d\u2019Oran, en Alg\u00e9rie, au d\u00e9but du XXe si\u00e8cle. Le mot a ensuite \u00e9t\u00e9 form\u00e9 \u00e0 partir de son nom, avec le suffixe \u00ab -ine \u00bb, comme pour d\u2019autres noms de fruits. Pourquoi \u201cSoculente\u201d ? : Dans les offres commerciales, Soculente semble \u00eatre une mani\u00e8re stylis\u00e9e d\u2019\u00e9voquer une cl\u00e9mentine tr\u00e8s succulente, donc particuli\u00e8rement douce et juteuse. Ce n\u2019est pas un terme botanique ni le nom d\u2019une vari\u00e9t\u00e9 historique au sens classique.\u00a0\u00bb<\/em> Alors : <span style=\"color: #ff6600;\"><strong>qui a eu cette id\u00e9e de jouer tant sur le sens que, sans doute, sur un certain accent ? Sachant que si j&rsquo;entre \u00ab\u00a0soculente\u00a0\u00bb dans Deepl&#8230; l&rsquo;IA de traduction me dit que cela signifie <em>succulentes<\/em>, mais ce serait&#8230; du roumain ! Or, la Roumanie n&rsquo;est pas productrice (hypoth\u00e8se : l&rsquo;auteur du terme serait donc un Espagnol d&rsquo;origine roumaine ? Le myst\u00e8re s&rsquo;\u00e9paissit devant l&rsquo;\u00e9tal!)<\/strong><\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22188\" src=\"https:\/\/francis-mizio.net\/wp-content\/uploads\/2026\/04\/15042019-13h54RueStJacEgStSeverin5eArrdt-936x1024.jpg\" alt=\"\" width=\"936\" height=\"1024\" srcset=\"https:\/\/francis-mizio.net\/wp-content\/uploads\/2026\/04\/15042019-13h54RueStJacEgStSeverin5eArrdt-936x1024.jpg 936w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2026\/04\/15042019-13h54RueStJacEgStSeverin5eArrdt-274x300.jpg 274w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2026\/04\/15042019-13h54RueStJacEgStSeverin5eArrdt-768x840.jpg 768w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2026\/04\/15042019-13h54RueStJacEgStSeverin5eArrdt-1404x1536.jpg 1404w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2026\/04\/15042019-13h54RueStJacEgStSeverin5eArrdt.jpg 1822w\" sizes=\"auto, (max-width: 936px) 100vw, 936px\" \/><strong><br \/>\n<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><em>Afin de nettoyer les 14 529 photos et 334 vid\u00e9os (\u00e0 la date du 1er mai 2025 lors de laquelle je d\u00e9cide de m&rsquo;astreindre \u00e0 ce projet) accumul\u00e9es depuis 2001 (date de mes premi\u00e8res photos num\u00e9riques), je passe en revue chaque jour la date du jour : c&rsquo;est-\u00e0-dire que par exemple en tapant (2 mai) dans le moteur de recherche de mon logiciel de stockage de photographies, apparaissent tous les 2 mai lors desquels j&rsquo;ai pris des photographies. Je peux donc virer les images inutiles (personnes et lieux totalement oubli\u00e9s, oubliables ou \u00e0 franchement oublier ou non identifiables, photographies sans un quelconque int\u00e9r\u00eat&#8230;), nettoyer ainsi ma phototh\u00e8que (et soulager de fa\u00e7on infinit\u00e9simale mon bilan carbone) en m&rsquo;entra\u00eenant \u00e0 un exercice de m\u00e9moire.<br \/>\nJe publie les photographies ici \u00e0 la minute pr\u00e8s (donn\u00e9e accessible dans les m\u00e9tadatas des images), comme un voyage instantan\u00e9 au travers du temps.<br \/>\n<\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Index des \u00ab\u00a0O\u00f9-\u00e9tais-je ?\u00a0\u00bb parus pour l&rsquo;instant :<\/strong><br \/>\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/05\/02\/ou-etais-je-le-bilan-dun-an-de-nettoyage-photo-numerique-et-de-plongee-memorielle\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] Bilan d&rsquo;un an de nettoyage photo-num\u00e9rique et de plong\u00e9e m\u00e9morielle<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/05\/01\/ou-etais-je-le-1er-mai-2018-devant-une-volee-de-pelerins-bouddhistes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 1er mai 2018, devant une vol\u00e9e de p\u00e9lerins bouddhistes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/29\/ou-etais-je-le-29-avril-2015-chez-jacques-prevert\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 29 avril 2015, chez Jacques Pr\u00e9vert<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/26\/ou-etais-je-le-26-avril-2022-devant-un-camion-venu-me-livrer-une-palette-de-mon-roman-desormais-gratuit\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 avril 2022, devant un camion venu me livrer une palette de mon avant-dernier roman (d\u00e9sormais gratuit)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/24\/ou-etais-je-le-24-avril-2025-devant-un-mysterieux-seau-de-gros-poissons-vides\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 avril 2025, devant un myst\u00e9rieux seau de gros poissons vid\u00e9s<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/22\/ou-etais-je-le-22-avril-2012-dans-une-voliere-a-papillons\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 22 avril 2012, dans une voli\u00e8re \u00e0 papillons<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/21\/ou-etais-je-le-21-avril-2023-devant-le-rocher-de-melusine\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 avril 2023, devant le rocher de M\u00e9lusine<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/20\/ou-etais-je-le-20-avril-2019-devant-un-caviardage-potache-et-polisson\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 avril 2019, devant un caviardage potache et polisson<\/a><\/li><li class=\"current\"><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/15\/ou-etais-je-le-15-avril-2019-a-paris-pris-par-ma-propre-ignorance-ma-betise-et-un-prejuge\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 15 avril 2019, \u00e0 Paris, pris par ma propre ignorance, ma b\u00eatise, un pr\u00e9jug\u00e9 et un myst\u00e8re<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/14\/ou-etais-je-le-14-avril-2024-jetais-devant-un-vieux-gros-truc-superbe-qui-menace-de-secrouler-et-a-besoin-de-nos-thunes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 avril 2024, j&rsquo;\u00e9tais devant un vieux gros truc superbe qui menace de s&rsquo;\u00e9crouler et \u00e0 besoin de nos thunes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/13\/ou-etais-je-le-13-avril-2023-face-a-un-panneau-equivoque-pour-qui-maitrise-mal-le-francais\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 13 avril 2023 face \u00e0 un panneau \u00e9quivoque pour qui ma\u00eetrise mal le fran\u00e7ais<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/11\/ou-etais-je-le-11-avril-2017-dans-le-theatre-musee-dali-a-figueres\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 avril 2017, dans le th\u00e9\u00e2tre-mus\u00e9e Dali \u00e0 Figu\u00e9r\u00e8s<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/10\/ou-etais-je-le-10-avril-2010-au-dessus-de-la-cour-de-mon-immeuble-ou-habitait-ce-satane-voisin\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 10 avril 2010, au-dessus de la cour de mon immeuble o\u00f9 habitait ce satan\u00e9 voisin<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/05\/ou-etais-je-le-5-avril-2020-devant-un-cimetiere-de-muscadet\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 5 avril 2020, devant un cimeti\u00e8re de muscadet<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/04\/ou-etais-je-le-4-avril-2019-devant-une-innovation-des-gilets-jaunes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 4 avril 2019, devant une innovation des Gilets Jaunes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/03\/ou-etais-je-le-3-avril-2006-devant-une-cuvette-wc-en-train-de-sevader\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 3 avril 2006, devant une cuvette WC en train de s&rsquo;\u00e9vader<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/26\/ou-etais-je-le-26-mars-2019-devant-un-probleme-de-vitrine-et-de-point-de-vue\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 mars 2019, devant un probl\u00e8me de vitrine et de point de vue<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/25\/ou-etais-je-le-25-mars-2022-devant-une-contrebasse-tordue\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 25 mars 2011, devant une contrebasse tordue<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/19\/ou-etais-je-le-19-mars-2022-devant-le-squelette-dun-serpent-geant\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 19 mars 2022, devant le squelette d&rsquo;un serpent g\u00e9ant<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/18\/ou-etais-je-le-18-mars-2022-devant-une-paire-de-fesses-geante\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 18 mars 2011, devant une paire de fesses g\u00e9antes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/12\/ou-etais-je-le-12-mars-2022-devant-un-antique-cas-de-harcelement-sexuel\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 12 mars 2022, devant un antique cas de harc\u00e8lement sexuel<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/08\/ou-etais-je-le-8-mars-2010-dans-un-train-devant-une-sorte-de-creature-fantastique\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 8 mars 2010, dans un train devant une sorte de cr\u00e9ature fantastique<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/05\/ou-etais-je-le-5-mars-2022-devant-un-alignement-orthodoxo-lunaire\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 5 mars 2022, devant un alignement orthodoxo-lunaire<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/04\/ou-etais-je-le-4-mars-2019-chez-moi-devant-un-arbre-qui-est-heureusement-tombe-du-bon-cote\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 4 mars 2019, chez moi devant un arbre qui est heureusement tomb\u00e9 du bon c\u00f4t\u00e9<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/03\/03\/ou-etais-je-le-3-mars-2022-devant-des-restes-de-confinement-civid\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 3 mars 2022, devant des traces de  gestes barri\u00e8res<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/02\/24\/ou-etais-je-le-24-fevrier-2018-chez-moi-avec-une-pipistrelle-endormie\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 f\u00e9vrier 2018, chez moi, avec une pipistrelle endormie<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/02\/14\/ou-etais-je-le-14-fevrier-2003-a-la-boule-noire-a-paris-avec-le-grand-fred-kassak\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 f\u00e9vrier 2003, \u00e0 la Boule Noire \u00e0 Paris avec le grand Fred Kassak<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/02\/11\/ou-etais-je-le-11-fevrier-2020-au-tribunal-de-nantes-et-jai-gagne\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 f\u00e9vrier 2020, au tribunal de Nantes \u2014 et j&rsquo;ai gagn\u00e9 !<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/24\/ou-etais-je-le-24-janvier-2005-sur-la-plage-du-diamant-en-martinique-pres-dun-monument-bouleversant\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 janvier 2005, sur la plage du Diamant en Martinique, pr\u00e8s d&rsquo;un monument bouleversant<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/16\/ou-etais-je-le-16-janvier-2002-devant-cookie-monster-dans-un-temple-bouddhiste\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 16 janvier 2002, devant Cookie Monster dans un temple taoiste<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/15\/ou-etais-je-le-15-janvier-2003-devant-des-tortues-des-galapos-en-train-de-forniquer\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 15 janvier 2003, devant des tortues des Galapos en train de forniquer<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/13\/ou-etais-je-le-13-janvier-2012-dans-une-tres-petite-librairie-en-train-de-danser-sur-une-musique-de-film\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 13 janvier 2012, dans une tr\u00e8s petite librairie en train de danser sur une musique de film<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/11\/ou-etais-je-le-11-janvier-2002-a-north-point-hong-kong-devant-des-echafaudages-en-bambous\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 janvier 2002, \u00e0 North Point, Hong-Kong, devant des \u00e9chafaudages en bambous<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/09\/ou-etais-je-le-9-janvier-2020-a-nantes-devant-un-superbe-parapluie-special-manifs-et-un-stand-de-slogans\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 9 janvier 2020, \u00e0 Nantes, devant un superbe parapluie sp\u00e9cial manifs (et un stand de slogans)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/08\/ou-etais-je-le-8-janvier-2012-a-nantes-en-train-de-savourer-du-pate-de-poney\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 8 janvier 2012, \u00e0 Nantes, en train de savourer du p\u00e2t\u00e9 de poney<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/07\/ou-etais-je-le-7-janvier-2025-devant-des-piranhas\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 7 janvier 2025, devant des piranhas<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/03\/ou-etais-je-le-3-janvier-2024-a-bruges-belgiqueen-train-de-vaincre-un-k2-dans-le-cadre-de-ma-pratique-de-latourex\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 3 janvier 2024, \u00e0 Bruges (Belgique) en train de vaincre un K2 dans le cadre de ma pratique de Latourex<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/01\/02\/ou-etais-je-le-2-janvier-2019-a-porto-portugal-devant-un-funiculaire\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 2 janvier 2019, \u00e0 Porto (Portugal) devant un funiculaire<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/12\/31\/ou-etais-je-le-31-decembre-2019-a-porto-portugal-devant-un-paon-lumineux\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 31 d\u00e9cembre 2019, \u00e0 Porto (Portugal) devant un paon lumineux<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/12\/30\/ou-etais-je-le-30-decembre-2011-a-nort-sur-erdre-44-en-train-de-repeter-une-conference-jazzy-sur-ennio-morricone\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 30 d\u00e9cembre 2011,  \u00e0 Nort-sur-Erdre (44) en train de r\u00e9p\u00e9ter une conf\u00e9rence jazzy sur Ennio Morricone<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/12\/23\/ou-etais-je-le-23-decembre-2010-sur-la-placa-reial-a-barcelone-devant-des-statues-vivantes-qui-avaient-remballe\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 23 d\u00e9cembre 2010, sur la Pla\u00e7a Reial \u00e0 Barcelone devant des statues vivantes qui avaient remball\u00e9<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/12\/22\/ou-etais-je-le-22-decembre-2011-dans-un-bunker-a-ecouter-marc-caro-presenter-ses-creations-musicales\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 22 d\u00e9cembre 2011,  dans un bunker \u00e0 \u00e9couter Marc Caro pr\u00e9senter ses cr\u00e9ations musicales<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/12\/10\/ou-etais-je-le-10-decembre-2019-au-centre-commercial-les-eleis-de-cherbourg-et-jetais-projete-au-dela-du-25\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 10 d\u00e9cembre 2019,  au centre commercial Les \u00c9leis de Cherbourg et j&rsquo;\u00e9tais projet\u00e9 au-del\u00e0 du 25<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/11\/07\/ou-etais-je-le-7-novembre-2024-dans-ma-cour-devant-une-palette-de-bouquins-absolument-geniaux\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 7 novembre 2024,  dans ma cour devant une palette de bouquins absolument g\u00e9niaux<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/11\/06\/ou-etais-je-le-6-novembre-2021-a-a-471438-0n-11436-2w-devant-des-mercis-a-marie-nld\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 6 novembre 2021, \u00e0 47\u00b014&rsquo;38.0&Prime;N 1\u00b014&rsquo;36.2&Prime;W devant des mercis \u00e0 Marie NLD<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/11\/01\/ou-etais-je-le-1er-novembre-2008-a-un-concert-de-peach-noise-groupe-frankzappatiste-dun-ami-denfance\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 1er novembre 2008,  \u00e0 un concert de Peach Noise, groupe frankzappatiste d&rsquo;un ami d&rsquo;enfance<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/31\/ou-etais-je-le-31-octobre-2019-dans-la-bouillasse-a-les-allards-dolus-doleron\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 31 octobre 2019 dans la bouillasse \u00e0 Les Allards (Dolus d&rsquo;Oleron)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/30\/ou-etais-je-le-30-octobre-2010-a-nantes-sur-le-trois-mats-barque-belem\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 30 octobre 2010 \u00e0 Nantes, sur le trois m\u00e2ts barque Belem<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/29\/ou-etais-je-le-29-octobre-2019-a-la-rochelle-sous-les-parapluies-de-octobre-rose\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 29 octobre 2019  \u00e0 La Rochelle sous les parapluies de \u00ab\u00a0Octobre rose\u00a0\u00bb<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/28\/ou-etais-je-le-28-octobre-2017-a-pointe-noire-congo-en-train-de-flipper-dans-les-toilettes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 28 octobre 2017,  \u00e0 Pointe Noire (Congo) en train de flipper dans les toilettes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/26\/ou-etais-je-le-26-octobre-2019-en-train-de-visiter-lexpo-le-chamane-et-la-pensee-de-la-foret\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 octobre 2019, en train de visiter l&rsquo;expo \u00ab\u00a0Le Chamane et la pens\u00e9e de la for\u00eat\u00a0\u00bb<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/25\/ou-etais-je-le-25-octobre-2003-a-collioure-devant-un-pigeon-lui-meme-devant-des-poissons\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 25 octobre 2003, \u00e0 Collioure devant un pigeon lui-m\u00eame devant des poissons<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/24\/ou-etais-je-le-24-octobre-2017-a-pointe-noire-congo-lisant-un-livre-dans-la-piece-ou-alain-mabanckou-la-ecrit\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 octobre 2017, \u00e0 Pointe Noire (Congo) lisant un livre dans la pi\u00e8ce o\u00f9 Alain Mabanckou l&rsquo;a \u00e9crit<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/19\/ou-etais-je-le-19-octobre-2014-dans-un-voilier-en-bois-au-large-de-pornic\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 19 octobre 2014, dans un voilier en bois au large de Pornic<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/18\/ou-etais-je-le-18-octobre-2020-dans-un-coucou-au-dessus-de-la-baule\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 18 octobre 2020, dans un coucou au-dessus de la Baule<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/11\/ou-etais-je-le-11-octobre-2014-a-nantes-devant-un-monstreux-composteur-en-acier\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 octobre 2014, \u00e0 Nantes, devant un monstreux composteur en acier<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/09\/ou-etais-je-le-09-octobre-visiblement-nulle-part\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 09 octobre, visiblement nulle part chaque 9 octobre depuis 24 ans<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/08\/ou-etais-je-le-08-octobre-2019-a-nantes-devant-une-boite-aux-lettres-qui-ma-fait-rire-avec-sa-precision\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 08 octobre 2019, \u00e0 Nantes, devant une bo\u00eete aux lettres qui m&rsquo;a fait rire avec sa pr\u00e9cision<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/06\/ou-etais-je-le-06-octobre-2004-devant-la-republique-qui-avait-deja-besoin-dun-coup-de-neuf\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 06 octobre 2004, devant la R\u00e9publique qui avait d\u00e9j\u00e0 besoin d&rsquo;un coup de neuf<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/04\/ou-etais-je-le-04-octobre-2008-devant-des-brouettes-decoratives-a-la-chartreuse-de-villeneuve-les-avignon\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 04 octobre 2008,  devant des brouettes d\u00e9coratives \u00e0 La Chartreuse de Villeneuve-l\u00e8s-Avignon<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/10\/03\/ou-etais-je-le-03-octobre-2009-a-pau-devant-des-graffitis\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 03 octobre 2009, \u00e0 Pau, devant des graffitis<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/24\/ou-etais-je-le-24-septembre-2021-a-cape-coast-un-des-pires-lieux-de-lhistoire\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 septembre 2021, \u00e0 Cape Coast, un des pires lieux de l&rsquo;Histoire<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/22\/ou-etais-je-le-22-septembre-2014-devant-un-bateau-mou-au-pellerin-44\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 22 septembre 2014, devant un bateau mou, au Pellerin (44)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/20\/ou-etais-je-le-20-septembre-2021-dans-un-helicoptere-des-forces-armees-ghaneennes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 septembre 2021, dans un h\u00e9licopt\u00e8re des forces arm\u00e9es ghan\u00e9ennes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/09\/ou-etais-je-le-09-septembre-2014-sur-un-paquebot-dans-le-port-de-gijon-espagne\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 09 septembre 2014, en reportage sur un paquebot dans le port de Gij\u00f3n (Espagne)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/07\/ou-etais-je-le-07-septembre-2003-devant-des-poubelles-relayant-une-action-de-lassociation-aides\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 07 septembre 2003, devant des poubelles relayant une action de l&rsquo;association AIDES<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/05\/ou-etais-je-le-05-septembre-2024-chez-moi-devant-le-premier-signe-de-lautomne\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 05 septembre 2024, chez moi, devant le premier signe de l&rsquo;automne<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/04\/ou-etais-je-le-04-septembre-2018-dans-le-cimetiere-denfants-de-pen-bron\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 04 septembre 2018, dans le cimeti\u00e8re d&rsquo;enfants de Pen Bron<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/09\/02\/ou-etais-je-le-02-septembre-2003-devant-king-kong-dans-le-jardin-des-tuileries-a-paris\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 02 septembre 2003, devant King Kong dans le jardin des Tuileries \u00e0 Paris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/21\/ou-etais-je-le-21-aout-2017-devant-une-photo-de-tomate\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 ao\u00fbt 2017, devant une photo de tomate<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/20\/ou-etais-je-le-20-aout-2013-dans-des-marais-salants-de-saint-molf-pres-de-guerande\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 ao\u00fbt 2013, dans des marais salants de Saint Molf, pr\u00e8s de Gu\u00e9rande<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/17\/ou-etais-je-le-17-aout-2023-a-castres-devant-la-porte-de-lagence-ou-jaurais-pu-attendre-godot\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 17 ao\u00fbt 2023, \u00e0 Castres, devant la porte de l&rsquo;agence o\u00f9 j&rsquo;aurais pu attendre Godot<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/16\/ou-etais-je-le-16-aout-2021-sur-la-plage-de-bregancon-devant-des-journalisets-en-short\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 16 ao\u00fbt 2021, sur la plage de Br\u00e9gan\u00e7on devant des journalistes en short<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/13\/ou-etais-je-le-13-aout-2014-a-la-peche-a-pied-en-train-de-me-peter-le-dos\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 13 ao\u00fbt 2014, \u00e0 la p\u00eache \u00e0 pied en train de me p\u00e9ter le dos<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/12\/ou-etais-je-le-12-aout-2023-devant-une-creation-florale-upcycling-inattendue\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 12 ao\u00fbt 2023, devant une cr\u00e9ation florale upcycling inattendue<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/10\/ou-etais-je-le-10-aout-2016-devant-un-choix-graphique-hasardeux\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 10 ao\u00fbt 2016, devant un choix graphique hasardeux<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/07\/ou-etais-je-le-07-aout-2019-devant-un-balayeur-de-plage\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 07 ao\u00fbt 2019, devant un balayeur de plage<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/06\/ou-etais-je-le-06-aout-2019-devant-une-expression-cachee\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 06 ao\u00fbt 2019, devant une expression cach\u00e9e<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/05\/ou-etais-je-le-04-aout-2014-en-danger-de-submersion-maritime-en-correze\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 05 ao\u00fbt 2014, en danger d&rsquo;inondation maritime&#8230; en Corr\u00e8ze<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/04\/ou-etais-je-le-04-aout-2023-devant-vals-qui-massurait-des-vacances-heureuses\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 04 ao\u00fbt 2023, devant Vals qui m&rsquo;assurait des vacances heureuses<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/03\/ou-etais-je-le-03-aout-2023-dans-une-barque\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 03 ao\u00fbt 2023, dans une barque<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/08\/01\/ou-etais-je-le-1er-aout-2017-devant-un-salon-de-coiffure-a-castelnaudary\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 1er ao\u00fbt 2017, devant un salon de coiffure \u00e0 Castelnaudary<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/30\/ou-etais-je-le-30-juillet-2017-sous-une-araignee-geante\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 30 juillet 2017, sous une araign\u00e9e g\u00e9ante<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/29\/ou-etais-je-le-29-juillet-2017-devant-une-annonce-carrement-ecoeuree\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 29 juillet 2017, devant une annonce carr\u00e9ment \u00e9c\u0153ur\u00e9e<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/28\/ou-etais-je-le-28-juillet-2004-sur-le-toit-du-bhv-a-paris\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 28 juillet 2004, sur le toit du BHV \u00e0 Paris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/27\/ou-etais-je-le-27-juillet-2021-devant-des-palourdes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 27 juillet 2021, devant des palourdes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/26\/ou-etais-je-le-26-juillet-2011-devant-un-scorpion-ardechois\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 juillet 2011, devant un scorpion ard\u00e9chois<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/25\/ou-etais-je-le-25-juillet-2003-dans-le-bureau-dun-ministere-ou-je-deperissais\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 25 juillet 2003, dans le bureau d&rsquo;un minist\u00e8re o\u00f9 je d\u00e9p\u00e9rissais<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/24\/ou-etais-je-le-24-juillet-2019-dans-une-chambre-avec-une-religieuse\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 juillet 2019, dans une chambre avec une religieuse<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/23\/ou-etais-je-le-23-juillet-2003-a-paris-plage\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 23 juillet 2003, \u00e0 Paris Plage<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/21\/ou-etais-je-le-21-juillet-2010-parmi-des-hallucinations-numeriques\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 juillet 2010, parmi des hallucinations num\u00e9riques<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/20\/ou-etais-je-le-20-juillet-2011-petrifie-dans-un-arbre\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 juillet 2011, p\u00e9trifi\u00e9 dans un arbre<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/19\/ou-etais-je-le-19-juillet-2008-avec-un-chien-jaune\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 19 juillet 2008, avec un chien jaune \u00e0 Concarneau<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/17\/ou-etais-je-le-17-juillet-2024-devant-un-presentoir-a-orange-qui-ma-declenche-lecriture-dun-livre\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 17 juillet 2024, devant un pr\u00e9sentoir \u00e0 orange (qui m&rsquo;a d\u00e9clench\u00e9 l&rsquo;\u00e9criture d&rsquo;un livre)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/14\/ou-etais-je-le-14-juillet-2008-au-large-de-brest-parmi-des-centaines-de-bateaux\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 juillet 2008, au large de Brest parmi des centaines de bateaux<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/12\/ou-etais-je-le-12-juillet-2004-sous-le-vent-en-maurienne\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 12 juillet 2004, sous le vent en Maurienne<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/11\/ou-etais-je-le-11-juillet-2016-en-train-de-fouiner-au-pied-dun-calvaire\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 juillet 2016, en train de fouiner au pied d&rsquo;un calvaire<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/08\/ou-etais-je-le-8-juillet-2023-dans-une-ferme-electrique\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 08 juillet 2023 , dans une \u00ab\u00a0ferme \u00e9lectrique\u00a0\u00bb<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/07\/ou-etais-je-le-7-juillet-2008-a-penmarch-devant-un-geant\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 07 juillet 2008, \u00e0 Penmarc&rsquo;h, devant un g\u00e9ant<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/04\/ou-etais-je-le-4-juillet-2019-devant-un-mini-stonehenge-a-barneville-carteret-cotentin\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 04 juillet 2019, devant un mini Stonehenge \u00e0 Barneville-Carteret (Cotentin)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/03\/ou-etais-je-le-3-juillet-2011-au-milieu-de-milliards-de-coccinelles\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 03 juillet 2011, au milieu de milliards de coccinelles<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/02\/ou-etais-je-le-2-juillet-2021-devant-un-singe-en-hiver\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 02 juillet 2021, devant un Singe en hiver<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/07\/01\/ou-etais-je-le-1er-juillet-2021-a-granville-et-ses-marins-pecheurs-en-greve\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 1er juillet 2021, \u00e0 Granville et ses marins-p\u00e9cheurs alors en gr\u00e8ve<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/28\/ou-etais-je-le-28-juin-2014-a-port-joinville-ile-dyeu\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 28 juin 2014, \u00e0 Port Joinville, \u00eele d&rsquo;Yeu<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/25\/ou-etais-je-le-25-juin-2011-a-un-concert-de-lulu-la-nantaise-a-vertou-44\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 25 juin 2011, \u00e0 un concert de Lulu La Nantaise \u00e0 Vertou (44)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/24\/ou-etais-je-le-24-juin-2010-devant-un-abattant-de-cuvette-de-wc-maryline-monroe\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 juin 2010, devant un abattant de cuvette de WC Maryline Monroe<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/23\/ou-etais-je-le-23-juin-2019-au-hellfest\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 23 juin 2019, au Hellfest<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/21\/ou-etais-je-le-21-juin-2008-a-un-concert-de-tokio-hotel\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 juin 2008, \u00e0 un concert de Tokio Hotel (!)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/17\/ou-etais-je-le-17-juin-2016-devant-le-casino-de-cherbourg\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 17 juin 2016, devant le casino de Cherbourg<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/15\/ou-etais-je-le-15-juin-2007-a-un-concert-de-vincent-malone-chanteur-pour-enfants\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 15 juin 2007, \u00e0 un concert de Vincent Malone, chanteur pour enfants<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/14\/ou-etais-je-le-14-juin-2005-devant-archie-shepp-et-jalal-des-last-poets\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 juin 2005, devant Archie Shepp et Jalal des Last Poets<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/12\/ou-etais-je-le-12-juin-2005-devant-la-tombe-de-jim-morrisson-au-cimetiere-parisien-du-pere-lachaise\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 12 juin 2005, devant la tombe de Jim Morrisson, au cimeti\u00e8re parisien du P\u00e8re Lachaise<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/11\/ou-etais-je-le-11-juin-2010-devant-une-performance-au-104-a-paris\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 juin 2010, devant une performance au \u00ab\u00a0104\u00a0\u00bb \u00e0 Paris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/10\/ou-etais-je-le-10-juin-2004-devant-un-plan-de-cannabis\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 10 juin 2004, devant un plan de cannabis<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/08\/ou-etais-je-le-8-juin-2004-sur-une-plage-de-nice\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 09 juin 2004, sur une plage de Nice<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/08\/ou-etais-je-le-8-juin-2023-devant-une-marine-le-pen-en-prison\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 08 juin 2023, devant une Marine Le Pen en prison<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/07\/ou-etais-je-le-07-juin-2023-dans-une-montgolfiere\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 07 juin 2023, dans une montgolfi\u00e8re<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/06\/ou-etais-je-le-06-juin-2023-au-chateau-damboise\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 06 juin 2023, au ch\u00e2teau d&rsquo;Amboise<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/06\/05\/devant-un-distributeur-de-sandwichs\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 05 juin 2023, devant un distributeur de sandwichs o\u00f9 soudain surgit la gastro-litt\u00e9rature<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/29\/ou-etais-je-le-29-mai-2022-au-capc-musee-dart-contemporain-de-bordeaux\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 29 mai 2022 : au CAPC, mus\u00e9e d&rsquo;art contemporain de Bordeaux<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/28\/ou-etais-je-le-28-mai-2007-rue-du-renard-au-pied-du-centre-pompidou-a-paris\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 28 mai 2007 : rue du Renard au pied du centre Pompidou \u00e0 Paris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/27\/ou-etais-je-le-27-mai-2022-devant-une-soucoupe-volante\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 27 mai 2022 : devant une soucoupe volante<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/26\/ou-etais-je-le-26-mai-2014-parmi-les-chauve-souris\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 mai 2014 : parmi les chauve-souris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/25\/ou-etais-je-le-25-mai-2013-dans-un-champ-en-seine-et-marne\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 25 mai 2013 : dans un champ, en Seine-et Marne<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/24\/ou-etais-je-le-24-mai-2003-devant-une-fontaine-a-lespignan-herault\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 mai 2003 : devant une fontaine, \u00e0 Lespignan, H\u00e9rault<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/23\/ou-etais-je-le-23-mai-2010-parmi-des-dinosaures-a-paris\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 23 mai 2010 : parmi des dinosaures, \u00e0 Paris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/22\/ou-etais-je-le-22-mai-2014-devant-un-squelette-de-velo\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 22 mai 2014 : devant un squelette de v\u00e9lo<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/21\/ou-etais-je-le-21-mai-2016-dans-une-boucherie-algerienne\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 mai 2016 : dans une boucherie alg\u00e9rienne<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/20\/ou-etais-je-le-20-mai-2011-dans-un-jardin-nantais\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 mai 2011 : dans un jardin nantais<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/19\/ou-etais-je-le-19-mai-2024-dans-les-vignes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 19 mai 2024 : dans les vignes de muscadet<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/18\/ou-etais-je-le-18-mai-2020-devant-lhotel-de-la-gare-a-cherbourg\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 18 mai 2020 : devant l&rsquo;h\u00f4tel de la gare, \u00e0 Cherbourg<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/17\/ou-etais-je-le-17-mai-2014-au-saint-louis-un-bar-nantais\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 17 mai 2014 : au Saint Louis, un bar nantais<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/16\/ou-etais-je-le-16-mai-2021-a-nozieres-en-ardeche\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 16 mai 2021 : \u00e0 Nozi\u00e8res, en Ard\u00e8che<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/15\/ou-etais-je-le-15-mai-2020-chez-moi-pres-de-ma-corde-a-linge\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 15 mai 2020 : chez moi, pr\u00e8s de ma corde \u00e0 linge<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/14\/ou-etais-je-le-14-mai-2019-place-du-bouffay-a-nantes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 mai 2019 : Place du Bouffay, \u00e0 Nantes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/13\/ou-etais-je-le-13-mai-2006-devant-la-cathedrale-damiens\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 13 mai 2006 : devant la Cath\u00e9drale d&rsquo;Amiens<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/12\/12052019-ou-etais-je-le-12-mai-2019-sur-le-terrain-contre-ma-maison\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 12 mai 2019 : sur le terrain contre ma maison<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/11\/11052018-ou-etais-je-le-11-mai-2018-sur-un-canal-a-bangkok\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 11 mai 2018 : sur un canal \u00e0 Bangkok<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/09\/100524-ou-etais-je-le-10-mai-2024\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 10 mai 2024 : dans un avion qui va atterrir \u00e0 Nantes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/09\/09052022-ou-etais-je-le-9-mai-2022-derriere-lecole-de-design-a-nantes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 09 mai 2022 : derri\u00e8re l&rsquo;\u00e9cole de design \u00e0 Nantes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/08\/080506-ou-etais-je-le-8-mai-2006-sur-un-pont-entre-le-quai-de-jemmapes-et-le-quai-de-valmy\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 08 mai 2006 : sur un pont entre le quai de Jemmapes et le quai de Valmy \u00e0 Paris<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/07\/070523-ou-etais-je-le-7-mai-2023-chez-ma-mere\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 07 mai 2023 : chez ma m\u00e8re \ud83d\ude41<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/06\/060510-ou-etais-je-le-6-mai-2010-dans-une-librairie-de-chateaudun-avec-jean-bernard-pouy\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 06 mai 2010 : dans une librairie de Ch\u00e2teaudun avec Jean-Bernard Pouy<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/05\/050524\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 05 mai 2024 : \u200e\u2068au pied de la vache morte<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/04\/040516\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 04 mai 2016 : \u200e\u2068chez moi, avec un combattant<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/03\/030517-ou-etais-je-le-3-mai\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 03 mai 2018 : \u200e\u2068au Surat Thani Government Office Center\u2069, \u2068Surat Thani (Tha\u00eflande)\u2069<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2025\/05\/02\/ou-etais-je-020517\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 02 mai 2017 : devant le ch\u00e2teau de Blandy-les-Tours (77)<\/a><\/li><\/ul><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Explications de ce projet m\u00e9moriel et nettoyeur num\u00e9rique en bas] Le 15 avril 2019 \u00e0 13h54, il y a 7 ans, j&rsquo;\u00e9tais rue St-Jacques \u00e0 Paris, en face de l&rsquo;\u00e9glise St-S\u00e9verin pris par ma propre ignorance, ma b\u00eatise, un pr\u00e9jug\u00e9 et un myst\u00e8re. En passant, je vois sur le trottoir l&rsquo;\u00e9tal d&rsquo;une \u00ab\u00a0\u00e9picerie arabe\u00a0\u00bb ces<\/p>\n","protected":false},"author":1,"featured_media":22188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40,5],"tags":[],"fm_constellation":[136,140],"class_list":["post-22186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ou-etais-je","category-news"],"acf":[],"share_on_mastodon":{"url":"https:\/\/piaille.fr\/@francismizio\/116408587998848578","error":""},"_links":{"self":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/22186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/comments?post=22186"}],"version-history":[{"count":10,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/22186\/revisions"}],"predecessor-version":[{"id":22198,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/22186\/revisions\/22198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media\/22188"}],"wp:attachment":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media?parent=22186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/categories?post=22186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/tags?post=22186"},{"taxonomy":"fm_constellation","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/fm_constellation?post=22186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}