{"id":22905,"date":"2026-09-02T09:29:29","date_gmt":"2026-09-02T07:29:29","guid":{"rendered":"https:\/\/francis-mizio.net\/?p=22905"},"modified":"2026-09-02T09:29:29","modified_gmt":"2026-09-02T07:29:29","slug":"a-paraitre-kiki-trimballe-bouba-23-methodes-de-manipulation-mises-en-scene-et-analysees","status":"publish","type":"post","link":"https:\/\/francis-mizio.net\/index.php\/2026\/09\/02\/a-paraitre-kiki-trimballe-bouba-23-methodes-de-manipulation-mises-en-scene-et-analysees\/","title":{"rendered":"\u00c0 PARA\u00ceTRE : \u00ab\u00a0Kiki trimballe Bouba &#8211;  23 m\u00e9thodes de manipulation mises en sc\u00e8ne et analys\u00e9es\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-450 alignleft\" src=\"https:\/\/le-niveau-baisse.fr\/wp-content\/uploads\/2026\/08\/nouvellecouvKikiBouba-212x300.png\" alt=\"\" width=\"400\" height=\"566\" \/>Vous a-t-on subtilement contraint sur un terminal de paiement num\u00e9rique \u00e0 donner un pourboire excessif ? Un vendeur vous a-t-il fait acqu\u00e9rir quelque chose que vous ne d\u00e9siriez pas ? Une personne a-t-elle \u00e0 ce point influ\u00e9 sur votre bonne volont\u00e9 que vous vous \u00eates retrouv\u00e9-e \u00e0 effectuer pour elle une lourde t\u00e2che ? Dans ce livre, au travers de 23 \u00ab\u00a0fabulettes\u00a0\u00bb d\u00e9monstratives (inspir\u00e9es des saynettes v\u00e9cues par le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nasr_Eddin_Hodja\" target=\"_blank\" rel=\"noopener\">c\u00e9l\u00e8bre personnage de la culture turque Nasr Eddin Hodja<\/a>), mettant en sc\u00e8ne les fameux personnages de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Effet_bouba-kiki\" target=\"_blank\" rel=\"noopener\">l&rsquo;effet \u00ab\u00a0Bouba &#8211; Kiki\u00a0\u00bb<\/a>, Francis Mizio vous fera d\u00e9couvrir et identifier comment on vous manipule au quotidien.<br \/>\n<em>Ce livre est en cours de r\u00e9daction et est \u00e0 para\u00eetre avant la fin de l&rsquo;ann\u00e9e aux <a href=\"https:\/\/le-niveau-baisse.fr\" target=\"_blank\" rel=\"noopener\">\u00c9ditions Le Niveau Baisse\u00a0<\/a>: le prix n&rsquo;est pas encore fix\u00e9, car il d\u00e9pendra du nombre de pages (environ 200) et de son poids pour l&rsquo;envoi postal.<\/em><br \/>\n&gt; <a href=\"mailto:contact@le-niveau-baisse.fr\" target=\"_blank\" rel=\"noopener\">Je suis int\u00e9ress\u00e9-e, tenez-moi au courant<\/a><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-178 size-full aligncenter\" src=\"https:\/\/le-niveau-baisse.fr\/wp-content\/uploads\/2026\/01\/LeNiveaubaisse.gif\" alt=\"\" width=\"400\" height=\"224\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-68\" src=\"https:\/\/le-niveau-baisse.fr\/wp-content\/uploads\/2026\/01\/LogoLNB-1024x166-2.png\" alt=\"\" width=\"430\" height=\"70\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous a-t-on subtilement contraint sur un terminal de paiement num\u00e9rique \u00e0 donner un pourboire excessif ? Un vendeur vous a-t-il fait acqu\u00e9rir quelque chose que vous ne d\u00e9siriez pas ? Une personne a-t-elle \u00e0 ce point influ\u00e9 sur votre bonne volont\u00e9 que vous vous \u00eates retrouv\u00e9-e \u00e0 effectuer pour elle une lourde t\u00e2che ? Dans<\/p>\n","protected":false},"author":1,"featured_media":22909,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,34,39,21,5],"tags":[],"fm_constellation":[],"class_list":["post-22905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books","category-editions-le-niveau-baisse","category-mes-bouquins","category-recos-livres","category-news"],"acf":[],"share_on_mastodon":{"url":"https:\/\/piaille.fr\/@francismizio\/117200268025869912","error":""},"_links":{"self":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/22905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/comments?post=22905"}],"version-history":[{"count":3,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/22905\/revisions"}],"predecessor-version":[{"id":22908,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/22905\/revisions\/22908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media\/22909"}],"wp:attachment":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media?parent=22905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/categories?post=22905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/tags?post=22905"},{"taxonomy":"fm_constellation","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/fm_constellation?post=22905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}