{"id":4799,"date":"2025-05-21T10:44:12","date_gmt":"2025-05-21T08:44:12","guid":{"rendered":"https:\/\/francis-mizio.net\/?p=4799"},"modified":"2026-04-11T10:07:38","modified_gmt":"2026-04-11T08:07:38","slug":"ou-etais-je-le-21-mai-2016-dans-une-boucherie-algerienne","status":"publish","type":"post","link":"https:\/\/francis-mizio.net\/index.php\/2025\/05\/21\/ou-etais-je-le-21-mai-2016-dans-une-boucherie-algerienne\/","title":{"rendered":"[O\u00f9 \u00e9tais-je le&#8230; ?] 21 mai 2016 : dans une boucherie alg\u00e9rienne"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">[Explications de ce projet m\u00e9moriel et nettoyeur num\u00e9rique sous l&rsquo;image]<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Le 21 mai 2016 \u00e0 10h44, il y a 9 ans, j&rsquo;\u00e9tais dans une boucherie alg\u00e9rienne de l&rsquo;\u00eele de Nantes. <\/strong>Boucherie qui,\u00a0je crois, n&rsquo;existe plus. Je venais chercher le mouton que j&rsquo;avais command\u00e9 pour r\u00e9pondre \u00e0 une vieille envie : celle de faire un m\u00e9choui dans mon jardin (Bilan : il n&rsquo;a pas fait beau ; j&rsquo;ai pellet\u00e9 des braises toute la journ\u00e9e sans pouvoir vraiment profiter de la quarantaine d&rsquo;amis venus ; heureusement un pote chirurgien s&rsquo;est occup\u00e9 de la d\u00e9coupe&#8230; \u2014 et puis apr\u00e8s, vous faites quoi du squelette ? Je n&rsquo;y avais pas pens\u00e9&#8230; R\u00e9fl\u00e9chissez bien et faites-vous conseiller avant de vous lancer dans un tel projet&#8230;).<br \/>\nLe boucher (un homme adorable et formidable, tr\u00e8s \u00e9rudit) au sourire lumineux sur la photographie est&#8230; instituteur. Son histoire est singuli\u00e8re. De m\u00e9moire : apr\u00e8s la guerre d&rsquo;Alg\u00e9rie, la France a recrut\u00e9 sous contrat avantageux pour plusieurs mois des instituteurs alg\u00e9riens afin de pallier une carence de personnels scolaires en France (en les logeant tr\u00e8s mal, toutefois). Et au terme du contrat, alors qu&rsquo;on leur avait promis une embauche, ils ont \u00e9t\u00e9 brusquement remerci\u00e9s et somm\u00e9s de retourner au bled, dans des villages o\u00f9 la vie \u00e9tait ni riche, ni plus s\u00e9duisante. Bref, comme le traitement des travailleurs alg\u00e9riens de la SNCF, les <a href=\"https:\/\/shs.cairn.info\/revue-apres-demain-2016-2-page-44?lang=fr\" target=\"_blank\" rel=\"noopener\">chibanis<\/a>&#8230;<br \/>\nLui, a voulu alors rester : pour se faire il a achet\u00e9 en urgence le premier commerce qui \u00e9tait disponible avec l&rsquo;aide financi\u00e8re de compatriotes, soit cette boucherie, qu&rsquo;il a alors ouverte du jour au lendemain sans aucune formation ni comp\u00e9tences dans le m\u00e9tier. Il racontait que les clients l&rsquo;aidaient, le conseillaient, faisaient preuve d&rsquo;une grande tol\u00e9rance sur son ignorance des pi\u00e8ces de boucherie&#8230;<br \/>\nAu fil des d\u00e9cennies, il a gard\u00e9 la boucherie et s&rsquo;est form\u00e9 seul, s&rsquo;est pris de go\u00fbt pour le m\u00e9tier avec philosophie au point de b\u00e9n\u00e9ficier de l&rsquo;estime de sa client\u00e8le et m\u00eame d&rsquo;une solide r\u00e9putation pour une belle carri\u00e8re r\u00e9ussie de boucher. Je crois qu&rsquo;\u00e0 l&rsquo;\u00e9poque de cette photographie il ne lui restait que quelques ann\u00e9es avant la retraite.<br \/>\nCette histoire des instituteurs alg\u00e9riens m&rsquo;\u00e9tait inconnue (c&rsquo;est un sujet \u00e0 mon sens tr\u00e8s int\u00e9ressant : un historien ou un journaliste pour l&rsquo;\u00e9crire ?). On a avec l&rsquo;Alg\u00e9rie encore clairement un paquet de trucs historiques et coloniaux \u00e0 se faire pardonner, sinon \u00e0 r\u00e9parer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4800 size-full\" src=\"https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/210516-10h44-scaled.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/210516-10h44-scaled.jpg 1920w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/210516-10h44-225x300.jpg 225w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/210516-10h44-768x1024.jpg 768w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/210516-10h44-1152x1536.jpg 1152w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/210516-10h44-1536x2048.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><em>Afin de nettoyer les 14 529 photos et 334 vid\u00e9os (\u00e0 la date du 1er mai 2025 lors de laquelle je d\u00e9cide de m&rsquo;astreindre \u00e0 ce projet) accumul\u00e9es depuis 2001 (date de mes premi\u00e8res photos num\u00e9riques), je passe en revue chaque jour la date du jour : c&rsquo;est-\u00e0-dire que par exemple en tapant (2 mai) dans le moteur de recherche, tous les 2 mai lors desquels j&rsquo;ai pris des photographies, apparaissent. Je peux donc virer les images inutiles (personnes et lieux totalement oubli\u00e9s, oubliables ou \u00e0 franchement oublier ou non identifiables, photographies sans un quelconque int\u00e9r\u00eat&#8230;), nettoyer ainsi ma phototh\u00e8que (et soulager de fa\u00e7on infinit\u00e9simale mon bilan carbone) en m&rsquo;entra\u00eenant \u00e0 un exercice de m\u00e9moire.<br \/>\nJe publie les photographies ici \u00e0 la minute pr\u00e8s (donn\u00e9e accessible dans les m\u00e9tadatas des images), comme un voyage instantan\u00e9 au travers du temps.<br \/>\n<\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Index des \u00ab\u00a0O\u00f9-\u00e9tais-je ?\u00a0\u00bb parus pour l&rsquo;instant :<\/strong><br \/>\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/05\/02\/ou-etais-je-le-bilan-dun-an-de-nettoyage-photo-numerique-et-de-plongee-memorielle\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] Bilan d&rsquo;un an de nettoyage photo-num\u00e9rique et de plong\u00e9e m\u00e9morielle<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/05\/01\/ou-etais-je-le-1er-mai-2018-devant-une-volee-de-pelerins-bouddhistes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 1er mai 2018, devant une vol\u00e9e de p\u00e9lerins bouddhistes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/29\/ou-etais-je-le-29-avril-2015-chez-jacques-prevert\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 29 avril 2015, chez Jacques Pr\u00e9vert<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/26\/ou-etais-je-le-26-avril-2022-devant-un-camion-venu-me-livrer-une-palette-de-mon-roman-desormais-gratuit\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 avril 2022, devant un camion venu me livrer une palette de mon avant-dernier roman (d\u00e9sormais gratuit)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/24\/ou-etais-je-le-24-avril-2025-devant-un-mysterieux-seau-de-gros-poissons-vides\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 avril 2025, devant un myst\u00e9rieux seau de gros poissons vid\u00e9s<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/22\/ou-etais-je-le-22-avril-2012-dans-une-voliere-a-papillons\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 22 avril 2012, dans une voli\u00e8re \u00e0 papillons<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/21\/ou-etais-je-le-21-avril-2023-devant-le-rocher-de-melusine\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 avril 2023, devant le rocher de M\u00e9lusine<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/20\/ou-etais-je-le-20-avril-2019-devant-un-caviardage-potache-et-polisson\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 avril 2019, devant un caviardage potache et polisson<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/15\/ou-etais-je-le-15-avril-2019-a-paris-pris-par-ma-propre-ignorance-ma-betise-et-un-prejuge\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 15 avril 2019, \u00e0 Paris, pris par ma propre ignorance, ma b\u00eatise, un pr\u00e9jug\u00e9 et un myst\u00e8re<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/14\/ou-etais-je-le-14-avril-2024-jetais-devant-un-vieux-gros-truc-superbe-qui-menace-de-secrouler-et-a-besoin-de-nos-thunes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 avril 2024, j&rsquo;\u00e9tais devant un vieux gros truc superbe qui menace de s&rsquo;\u00e9crouler et \u00e0 besoin de nos thunes<\/a><\/li><\/ul><\/p>\n<p><em>Si les tout premiers (s\u00e9rie commenc\u00e9e le 2 mai 2025) ne s&rsquo;affichent pas (j&rsquo;ignore pourquoi), &gt; <a href=\"https:\/\/francis-mizio.net\/index.php\/category\/news\/ou-etais-je\/\" target=\"_blank\" rel=\"noopener\">la rubrique compl\u00e8te est ici<\/a>.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Explications de ce projet m\u00e9moriel et nettoyeur num\u00e9rique sous l&rsquo;image] Le 21 mai 2016 \u00e0 10h44, il y a 9 ans, j&rsquo;\u00e9tais dans une boucherie alg\u00e9rienne de l&rsquo;\u00eele de Nantes. Boucherie qui,\u00a0je crois, n&rsquo;existe plus. Je venais chercher le mouton que j&rsquo;avais command\u00e9 pour r\u00e9pondre \u00e0 une vieille envie : celle de faire un m\u00e9choui<\/p>\n","protected":false},"author":1,"featured_media":4800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40,5],"tags":[],"fm_constellation":[136,140],"class_list":["post-4799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ou-etais-je","category-news"],"acf":[],"share_on_mastodon":{"url":"https:\/\/piaille.fr\/@francismizio\/114544939366531399","error":""},"_links":{"self":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/4799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/comments?post=4799"}],"version-history":[{"count":5,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/4799\/revisions"}],"predecessor-version":[{"id":4920,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/4799\/revisions\/4920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media\/4800"}],"wp:attachment":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media?parent=4799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/categories?post=4799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/tags?post=4799"},{"taxonomy":"fm_constellation","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/fm_constellation?post=4799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}