{"id":4869,"date":"2025-05-24T18:13:37","date_gmt":"2025-05-24T16:13:37","guid":{"rendered":"https:\/\/francis-mizio.net\/?p=4869"},"modified":"2026-04-11T10:07:38","modified_gmt":"2026-04-11T08:07:38","slug":"ou-etais-je-le-24-mai-2003-devant-une-fontaine-a-lespignan-herault","status":"publish","type":"post","link":"https:\/\/francis-mizio.net\/index.php\/2025\/05\/24\/ou-etais-je-le-24-mai-2003-devant-une-fontaine-a-lespignan-herault\/","title":{"rendered":"[O\u00f9 \u00e9tais-je le&#8230; ?] 24 mai 2003 : devant une fontaine, \u00e0 Lespignan, H\u00e9rault"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">[Explications de ce projet m\u00e9moriel et nettoyeur num\u00e9rique sous l&rsquo;image]<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Le 24 mai 2003 \u00e0 18h13, il y a 22 ans, j&rsquo;\u00e9tais devant une fontaine \u00e0 Lespignan, dans l&rsquo;H\u00e9rault (34)<\/strong>. J&rsquo;ai eu beaucoup de mal \u00e0 identifier le lieu en fouinant sur le web \u00e0 partir de deux autres photographies pr\u00e9c\u00e9dentes (un village dans un paysage du Sud, de vieilles pierres), du type de la fontaine, et du nom du magasin (qui ne doit plus exister). Je suis d\u00e9sormais \u00e0 peu pr\u00e8s certain du lieu (mon appareil photo n&rsquo;avait pas de g\u00e9olocalisation et je n&rsquo;avais pas renseign\u00e9 l&rsquo;image en l&rsquo;archivant), mais je peux me tromper. Nous allions, mon amoureuse de l&rsquo;\u00e9poque et moi de je ne sais o\u00f9, apr\u00e8s \u00eatre all\u00e9 et avoir fait je ne sais quoi. Une pause sur la route qui nous ramenait ou nous \u00e9loignait \u00e0 l&rsquo;\u00e9poque de la Dordogne o\u00f9 nous demeurions.<br \/>\nCette photo n&rsquo;a pas vraiment int\u00e9r\u00eat. Pourquoi l&rsquo;ai-je prise ? Est-ce \u00e0 cause du nom de la boutique ? Qu&rsquo;en dire ? On peut toutefois, \u00e0 partir d&rsquo;elle, tout imaginer : les gamins sur la place ont bien grandi. Il y a en un en prison maintenant pour avoir abim\u00e9 un flic lors d&rsquo;une manifestation, un autre est commercial dans les cuisines am\u00e9nag\u00e9es. Il est en plein divorce et \u00e7a se passe mal. On esp\u00e8re qu&rsquo;il aura la garde. Le troisi\u00e8me \u00e0 gauche est m\u00e9decin, r\u00e9put\u00e9 pour son traitement des mycoses. \u00c0 moins que ce ne soit carr\u00e9ment autre chose : un agriculteur, un enseignant, un int\u00e9rimaire en usine. Ou alors&#8230; J&rsquo;aime souvent imaginer ce que sont devenus les inconnus ainsi crois\u00e9s. J&rsquo;aime aussi penser qu&rsquo;un des trois habite peut-\u00eatre aujourd&rsquo;hui pr\u00e8s de chez moi et que nous ne saurons jamais que nos existences se sont crois\u00e9es quelques secondes, ou que je l&rsquo;ai c\u00f4toy\u00e9 une minute 35 douze ans apr\u00e8s dans le m\u00e9tro \u00e0 Paris, ligne 3, 2e rame. Enfin, ce genre de choses comme il en existe dans des romans ou les vieux films de Claude Lelouch. Ce genre de choses dont j&rsquo;ai le go\u00fbt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4870 size-full\" src=\"https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/lespignan24050318h13-.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/lespignan24050318h13-.jpg 640w, https:\/\/francis-mizio.net\/wp-content\/uploads\/2025\/05\/lespignan24050318h13--300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><em>Afin de nettoyer les 14 529 photos et 334 vid\u00e9os (\u00e0 la date du 1er mai 2025 lors de laquelle je d\u00e9cide de m&rsquo;astreindre \u00e0 ce projet) accumul\u00e9es depuis 2001 (date de mes premi\u00e8res photos num\u00e9riques), je passe en revue chaque jour la date du jour : c&rsquo;est-\u00e0-dire que par exemple en tapant (2 mai) dans le moteur de recherche, tous les 2 mai lors desquels j&rsquo;ai pris des photographies, apparaissent. Je peux donc virer les images inutiles (personnes et lieux totalement oubli\u00e9s, oubliables ou \u00e0 franchement oublier ou non identifiables, photographies sans un quelconque int\u00e9r\u00eat&#8230;), nettoyer ainsi ma phototh\u00e8que (et soulager de fa\u00e7on infinit\u00e9simale mon bilan carbone) en m&rsquo;entra\u00eenant \u00e0 un exercice de m\u00e9moire.<br \/>\nJe publie les photographies ici \u00e0 la minute pr\u00e8s (donn\u00e9e accessible dans les m\u00e9tadatas des images), comme un voyage instantan\u00e9 au travers du temps.<br \/>\n<\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Index des \u00ab\u00a0O\u00f9-\u00e9tais-je ?\u00a0\u00bb parus pour l&rsquo;instant :<\/strong><br \/>\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/05\/02\/ou-etais-je-le-bilan-dun-an-de-nettoyage-photo-numerique-et-de-plongee-memorielle\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] Bilan d&rsquo;un an de nettoyage photo-num\u00e9rique et de plong\u00e9e m\u00e9morielle<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/05\/01\/ou-etais-je-le-1er-mai-2018-devant-une-volee-de-pelerins-bouddhistes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 1er mai 2018, devant une vol\u00e9e de p\u00e9lerins bouddhistes<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/29\/ou-etais-je-le-29-avril-2015-chez-jacques-prevert\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 29 avril 2015, chez Jacques Pr\u00e9vert<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/26\/ou-etais-je-le-26-avril-2022-devant-un-camion-venu-me-livrer-une-palette-de-mon-roman-desormais-gratuit\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 26 avril 2022, devant un camion venu me livrer une palette de mon avant-dernier roman (d\u00e9sormais gratuit)<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/24\/ou-etais-je-le-24-avril-2025-devant-un-mysterieux-seau-de-gros-poissons-vides\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 24 avril 2025, devant un myst\u00e9rieux seau de gros poissons vid\u00e9s<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/22\/ou-etais-je-le-22-avril-2012-dans-une-voliere-a-papillons\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 22 avril 2012, dans une voli\u00e8re \u00e0 papillons<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/21\/ou-etais-je-le-21-avril-2023-devant-le-rocher-de-melusine\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 21 avril 2023, devant le rocher de M\u00e9lusine<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/20\/ou-etais-je-le-20-avril-2019-devant-un-caviardage-potache-et-polisson\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 20 avril 2019, devant un caviardage potache et polisson<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/15\/ou-etais-je-le-15-avril-2019-a-paris-pris-par-ma-propre-ignorance-ma-betise-et-un-prejuge\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 15 avril 2019, \u00e0 Paris, pris par ma propre ignorance, ma b\u00eatise, un pr\u00e9jug\u00e9 et un myst\u00e8re<\/a><\/li><li><a href=\"https:\/\/francis-mizio.net\/index.php\/2026\/04\/14\/ou-etais-je-le-14-avril-2024-jetais-devant-un-vieux-gros-truc-superbe-qui-menace-de-secrouler-et-a-besoin-de-nos-thunes\/\">[O\u00f9 \u00e9tais-je le&#8230; ?] 14 avril 2024, j&rsquo;\u00e9tais devant un vieux gros truc superbe qui menace de s&rsquo;\u00e9crouler et \u00e0 besoin de nos thunes<\/a><\/li><\/ul><\/p>\n<p><em>Si les tout premiers (s\u00e9rie commenc\u00e9e le 2 mai 2025) ne s&rsquo;affichent pas (j&rsquo;ignore pourquoi), &gt; <a href=\"https:\/\/francis-mizio.net\/index.php\/category\/news\/ou-etais-je\/\" target=\"_blank\" rel=\"noopener\">la rubrique compl\u00e8te est ici<\/a>.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Explications de ce projet m\u00e9moriel et nettoyeur num\u00e9rique sous l&rsquo;image] Le 24 mai 2003 \u00e0 18h13, il y a 22 ans, j&rsquo;\u00e9tais devant une fontaine \u00e0 Lespignan, dans l&rsquo;H\u00e9rault (34). J&rsquo;ai eu beaucoup de mal \u00e0 identifier le lieu en fouinant sur le web \u00e0 partir de deux autres photographies pr\u00e9c\u00e9dentes (un village dans un<\/p>\n","protected":false},"author":1,"featured_media":4870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40,5],"tags":[],"fm_constellation":[136,140],"class_list":["post-4869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ou-etais-je","category-news"],"acf":[],"share_on_mastodon":{"url":"https:\/\/piaille.fr\/@francismizio\/114563703850105590","error":""},"_links":{"self":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/4869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/comments?post=4869"}],"version-history":[{"count":6,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/4869\/revisions"}],"predecessor-version":[{"id":4917,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/posts\/4869\/revisions\/4917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media\/4870"}],"wp:attachment":[{"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/media?parent=4869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/categories?post=4869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/tags?post=4869"},{"taxonomy":"fm_constellation","embeddable":true,"href":"https:\/\/francis-mizio.net\/index.php\/wp-json\/wp\/v2\/fm_constellation?post=4869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}